{"id":281,"date":"2023-04-28T19:41:52","date_gmt":"2023-04-28T19:41:52","guid":{"rendered":"https:\/\/idem.org.pe\/blog\/?p=281"},"modified":"2023-04-28T19:42:06","modified_gmt":"2023-04-28T19:42:06","slug":"el-arbitraje","status":"publish","type":"post","link":"https:\/\/idem.org.pe\/blog\/el-arbitraje\/","title":{"rendered":"El arbitraje como mecanismo de resoluci\u00f3n de controversias en nuestros contratos"},"content":{"rendered":"<p>Por <a href=\"https:\/\/www.arbitrajeccl.com.pe\/speaker\/luis-alonso-caceres-lopez\">Luis Alonso C\u00e1ceres L\u00f3pez<\/a>, <em>Secretario Arbitral del Centro de Arbitraje Nacional e Internacional de la C\u00e1mara de Comercio de Lima.<\/em><\/p>\n<p>T\u00f3mese su tiempo y lea con atenci\u00f3n. Lo que debemos tener en cuenta para pactar al arbitraje como mecanismo de resoluci\u00f3n de controversias en nuestros contratos.<\/p>\n<p>Imaginemos por un momento que el Poder Judicial o la tambi\u00e9n llamada jurisdicci\u00f3n ordinaria es una lluvia que va a empapar a todos aquellos conflictos que se originan en la sociedad, es decir cualquier controversia que se origine, por regla general, debe ser resuelta por un juez.<\/p>\n<p>Estando en esta lluvia, el ordenamiento jur\u00eddico nos brinda \u2013 entre otros &#8211; un paraguas llamado arbitraje y que se materializa a trav\u00e9s de la celebraci\u00f3n del convenio arbitral. En ese orden de ideas, el arbitraje se constituye como un mecanismo alternativo al Poder Judicial para resolver controversias respecto de una determinada relaci\u00f3n jur\u00eddica. Quien resolver\u00e1 la controversia ser\u00e1 un sujeto privado llamado \u00e1rbitro quien es nombrado, en principio, por las partes, el cual emitir\u00e1 un laudo arbitral. La puerta de ingreso o la llave para tener este paraguas se le denominada cl\u00e1usula o convenio arbitral.<\/p>\n<p>Qu\u00e9 debemos tener en cuenta para acordar un convenio arbitral:<\/p>\n<p>Considero que la redacci\u00f3n de un convenio o cl\u00e1usula arbitral debe seguir estas dos frases: \u201ccuanto m\u00e1s simple es mejor\u201d y \u201cmenos es m\u00e1s\u201d. Tengamos siempre en mente que buscamos que el arbitraje se desarrolle correctamente, y que el convenio arbitral sea eficaz.<\/p>\n<p>En esa l\u00ednea, debemos centrarnos primero en analizar frente a qu\u00e9 tipo de contrato nos encontramos. Al respecto, dado los altos costos que implica el inicio y persecuci\u00f3n de un proceso arbitral, tal vez no ser\u00eda conveniente pactar un convenio arbitral en un contrato de arrendamiento con una renta peque\u00f1a, por ejemplo, pues las eventuales controversias que surjan de este son, en su mayor\u00eda, vinculadas al desalojo y el pago de rentas. La evaluaci\u00f3n de incluir o no un convenio arbitral depender\u00e1 en gran medida de la especializaci\u00f3n que se requerir\u00e1 para resolver las eventuales controversias que se susciten. En algunos casos tambi\u00e9n acordar un arbitraje constituye una limitante para ejecutar el contrato. En este \u00faltimo caso tenemos, por ejemplo, a una transacci\u00f3n extrajudicial, que por su solo m\u00e9rito constituye un t\u00edtulo ejecutivo.<\/p>\n<p>El n\u00famero de \u00e1rbitros tambi\u00e9n deber\u00eda seguir la l\u00f3gica anterior, esto es, cuanto m\u00e1s compleja la relaci\u00f3n contractual y las posibles controversias que podr\u00edan surgir, el n\u00famero de \u00e1rbitros deber\u00eda aumentar. La Ley de Arbitraje Peruana, no establece una limitaci\u00f3n al n\u00famero de \u00e1rbitros, pero lo com\u00fan es acordar que se nombre uno o tres.<\/p>\n<p>Seguidamente, debemos analizar si acudimos a un arbitraje ad hoc o a uno institucional o administrado por una instituci\u00f3n arbitral. El arbitraje ad hoc, sin duda, va a generar mayores costos y recursos que encarecen el proceso. Por ejemplo, los costos de tramitar la notificaci\u00f3n de la solicitud de arbitraje al demandado y las dem\u00e1s notificaciones, el eventual pedido de nombramiento residual ante la C\u00e1mara de Comercio del \u00e1rbitro del demandado o del Presidente del Tribunal Arbitral, de ser el caso, y \u2013 lo m\u00e1s importante -, la falta de regulaci\u00f3n y el establecimiento de tablas de los gastos arbitrales, lo cual evidentemente puede prestarse para un abuso de los \u00e1rbitros y de las secretar\u00edas ad hoc para fijar honorarios excesivos o poco razonables.<\/p>\n<p>Vista esta realidad, recomiendo acordar un arbitraje institucional ante una instituci\u00f3n arbitral de prestigio en el mercado. Diversas c\u00e1maras de comercio o gremios profesionales han implementado centros de arbitraje a los cuales se puede recurrir, as\u00ed como tambi\u00e9n, en muchos casos, han elaborado reglamentos arbitrales modernos.<\/p>\n<p>La seguridad que nos brinda el arbitraje institucional no solo est\u00e1 relacionada a los gastos arbitrales (honorarios de los \u00e1rbitros y gastos de la instituci\u00f3n). Debemos tener presente que una instituci\u00f3n arbitral normalmente cuenta con personal capacitado para administrar los procesos arbitrales a su cargo, tienen infraestructura, han creado softwares y otros para virtualizar y agilizar los procesos, cuentan con consejos o cortes de arbitraje que se encargan de supervisar las conductas no solo del personal de la instituci\u00f3n, sino tambi\u00e9n de los \u00e1rbitros, entre otros. En la mayor\u00eda de casos, son las instituciones arbitrales quienes impulsan las mejores pr\u00e1cticas para la conducci\u00f3n efectiva de los arbitrajes y ello es tomado en cuenta por los dem\u00e1s operadores del sistema.<\/p>\n<p>Para concluir este breve ensayo, debemos tener en cuenta lo que no debemos acordar en el convenio arbitral. Por un lado, no acordemos plazos de duraci\u00f3n del arbitraje, pues podr\u00eda dar lugar a un sin n\u00famero de problemas con el tr\u00e1mite del arbitraje. Cuidar la redacci\u00f3n de la cl\u00e1usula, evitando, por ejemplo, acordar un arbitraje institucional ante una instituci\u00f3n que no existe o poner un nombre distinto. En la medida de lo posible, no establecer requisitos para los \u00e1rbitros, y si se hace, que estos sean (i) espec\u00edficos, (ii) razonables, y (iii) evitar colocar requisitos que no puedan acreditarse de manera objetiva, u otros que simplemente no existan en el mercado. Si se van a excluir determinadas controversias de la competencia de los \u00e1rbitros, deber\u00edan especificarse con toda claridad. Tener cuidado con acordar la aplicaci\u00f3n de normas jur\u00eddicas que no guardan relaci\u00f3n con el contrato, y tambi\u00e9n evitar establecer una sede del proceso poco amigable con el arbitraje que permita, por ejemplo, la intervenci\u00f3n del Poder Judicial en el curso del proceso.<\/p>\n<p>En cualquier caso, recomiendo que, a manera de gu\u00eda, tomemos las llamadas cl\u00e1usulas arbitrales modelo que publicitan las diversas instituciones arbitrales en sus p\u00e1ginas web o en sus reglamentos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Luis Alonso C\u00e1ceres L\u00f3pez, Secretario Arbitral del Centro de Arbitraje Nacional e Internacional de la C\u00e1mara de Comercio de Lima. T\u00f3mese su tiempo y lea con atenci\u00f3n. Lo que debemos tener en cuenta para pactar al arbitraje como mecanismo de resoluci\u00f3n de controversias en nuestros contratos. Imaginemos por un momento que el Poder Judicial [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":196,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El arbitraje como mecanismo de resoluci\u00f3n de controversias en nuestros contratos - Idem<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/idem.org.pe\/blog\/el-arbitraje\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El arbitraje como mecanismo de resoluci\u00f3n de controversias en nuestros contratos - Idem\" \/>\n<meta property=\"og:description\" content=\"Por Luis Alonso C\u00e1ceres L\u00f3pez, Secretario Arbitral del Centro de Arbitraje Nacional e Internacional de la C\u00e1mara de Comercio de Lima. T\u00f3mese su tiempo y lea con atenci\u00f3n. Lo que debemos tener en cuenta para pactar al arbitraje como mecanismo de resoluci\u00f3n de controversias en nuestros contratos. Imaginemos por un momento que el Poder Judicial [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/idem.org.pe\/blog\/el-arbitraje\/\" \/>\n<meta property=\"og:site_name\" content=\"Idem\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-28T19:41:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-28T19:42:06+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/idem.org.pe\/blog\/wp-content\/uploads\/2022\/08\/Blog-Idem-Post-1-y-2-10-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1351\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"idem\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"idem\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/idem.org.pe\/blog\/el-arbitraje\/\",\"url\":\"https:\/\/idem.org.pe\/blog\/el-arbitraje\/\",\"name\":\"El arbitraje como mecanismo de resoluci\u00f3n de controversias en nuestros contratos - Idem\",\"isPartOf\":{\"@id\":\"https:\/\/idem.org.pe\/blog\/#website\"},\"datePublished\":\"2023-04-28T19:41:52+00:00\",\"dateModified\":\"2023-04-28T19:42:06+00:00\",\"author\":{\"@id\":\"https:\/\/idem.org.pe\/blog\/#\/schema\/person\/73271f1d6f50978f3f824a6b50210561\"},\"breadcrumb\":{\"@id\":\"https:\/\/idem.org.pe\/blog\/el-arbitraje\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/idem.org.pe\/blog\/el-arbitraje\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/idem.org.pe\/blog\/el-arbitraje\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/idem.org.pe\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El arbitraje como mecanismo de resoluci\u00f3n de controversias en nuestros contratos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/idem.org.pe\/blog\/#website\",\"url\":\"https:\/\/idem.org.pe\/blog\/\",\"name\":\"Idem\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/idem.org.pe\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/idem.org.pe\/blog\/#\/schema\/person\/73271f1d6f50978f3f824a6b50210561\",\"name\":\"idem\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/idem.org.pe\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7a44628d5db416c2ff5df18ee0eec73a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7a44628d5db416c2ff5df18ee0eec73a?s=96&d=mm&r=g\",\"caption\":\"idem\"},\"sameAs\":[\"http:\/\/idem.org.pe\/blog\"],\"url\":\"https:\/\/idem.org.pe\/blog\/author\/idem\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El arbitraje como mecanismo de resoluci\u00f3n de controversias en nuestros contratos - Idem","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/idem.org.pe\/blog\/el-arbitraje\/","og_locale":"es_ES","og_type":"article","og_title":"El arbitraje como mecanismo de resoluci\u00f3n de controversias en nuestros contratos - Idem","og_description":"Por Luis Alonso C\u00e1ceres L\u00f3pez, Secretario Arbitral del Centro de Arbitraje Nacional e Internacional de la C\u00e1mara de Comercio de Lima. T\u00f3mese su tiempo y lea con atenci\u00f3n. Lo que debemos tener en cuenta para pactar al arbitraje como mecanismo de resoluci\u00f3n de controversias en nuestros contratos. Imaginemos por un momento que el Poder Judicial [&hellip;]","og_url":"https:\/\/idem.org.pe\/blog\/el-arbitraje\/","og_site_name":"Idem","article_published_time":"2023-04-28T19:41:52+00:00","article_modified_time":"2023-04-28T19:42:06+00:00","og_image":[{"width":2560,"height":1351,"url":"http:\/\/idem.org.pe\/blog\/wp-content\/uploads\/2022\/08\/Blog-Idem-Post-1-y-2-10-scaled-1.jpg","type":"image\/jpeg"}],"author":"idem","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"idem","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/idem.org.pe\/blog\/el-arbitraje\/","url":"https:\/\/idem.org.pe\/blog\/el-arbitraje\/","name":"El arbitraje como mecanismo de resoluci\u00f3n de controversias en nuestros contratos - Idem","isPartOf":{"@id":"https:\/\/idem.org.pe\/blog\/#website"},"datePublished":"2023-04-28T19:41:52+00:00","dateModified":"2023-04-28T19:42:06+00:00","author":{"@id":"https:\/\/idem.org.pe\/blog\/#\/schema\/person\/73271f1d6f50978f3f824a6b50210561"},"breadcrumb":{"@id":"https:\/\/idem.org.pe\/blog\/el-arbitraje\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/idem.org.pe\/blog\/el-arbitraje\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/idem.org.pe\/blog\/el-arbitraje\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/idem.org.pe\/blog\/"},{"@type":"ListItem","position":2,"name":"El arbitraje como mecanismo de resoluci\u00f3n de controversias en nuestros contratos"}]},{"@type":"WebSite","@id":"https:\/\/idem.org.pe\/blog\/#website","url":"https:\/\/idem.org.pe\/blog\/","name":"Idem","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/idem.org.pe\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/idem.org.pe\/blog\/#\/schema\/person\/73271f1d6f50978f3f824a6b50210561","name":"idem","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/idem.org.pe\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7a44628d5db416c2ff5df18ee0eec73a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7a44628d5db416c2ff5df18ee0eec73a?s=96&d=mm&r=g","caption":"idem"},"sameAs":["http:\/\/idem.org.pe\/blog"],"url":"https:\/\/idem.org.pe\/blog\/author\/idem\/"}]}},"_links":{"self":[{"href":"https:\/\/idem.org.pe\/blog\/wp-json\/wp\/v2\/posts\/281"}],"collection":[{"href":"https:\/\/idem.org.pe\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/idem.org.pe\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/idem.org.pe\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/idem.org.pe\/blog\/wp-json\/wp\/v2\/comments?post=281"}],"version-history":[{"count":1,"href":"https:\/\/idem.org.pe\/blog\/wp-json\/wp\/v2\/posts\/281\/revisions"}],"predecessor-version":[{"id":282,"href":"https:\/\/idem.org.pe\/blog\/wp-json\/wp\/v2\/posts\/281\/revisions\/282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/idem.org.pe\/blog\/wp-json\/wp\/v2\/media\/196"}],"wp:attachment":[{"href":"https:\/\/idem.org.pe\/blog\/wp-json\/wp\/v2\/media?parent=281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/idem.org.pe\/blog\/wp-json\/wp\/v2\/categories?post=281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/idem.org.pe\/blog\/wp-json\/wp\/v2\/tags?post=281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}